{"id":3930,"date":"2023-03-12T03:35:02","date_gmt":"2023-03-12T02:35:02","guid":{"rendered":"https:\/\/lumieredubois.com\/custom-block\/footer\/"},"modified":"2026-04-03T13:54:39","modified_gmt":"2026-04-03T11:54:39","slug":"footer","status":"publish","type":"custom_blocks","link":"https:\/\/lumieredubois.com\/en\/custom-block\/footer\/","title":{"rendered":"Footer"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3930\" class=\"elementor elementor-3930 elementor-122\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04a0a59 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"04a0a59\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f21e9dd dark-color\" data-id=\"f21e9dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-735f52c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"735f52c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-41c2a3a\" data-id=\"41c2a3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e034062 elementor-widget elementor-widget-image\" data-id=\"e034062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"749\" height=\"750\" src=\"https:\/\/lumieredubois.com\/wp-content\/uploads\/2025\/05\/camere-champoluc-ayas.png\" class=\"attachment-large size-large wp-image-2776\" alt=\"camere a champoluc\" srcset=\"https:\/\/lumieredubois.com\/wp-content\/uploads\/2025\/05\/camere-champoluc-ayas.png 749w, https:\/\/lumieredubois.com\/wp-content\/uploads\/2025\/05\/camere-champoluc-ayas-300x300.png 300w, https:\/\/lumieredubois.com\/wp-content\/uploads\/2025\/05\/camere-champoluc-ayas-150x150.png 150w, https:\/\/lumieredubois.com\/wp-content\/uploads\/2025\/05\/camere-champoluc-ayas-600x600.png 600w, https:\/\/lumieredubois.com\/wp-content\/uploads\/2025\/05\/camere-champoluc-ayas-550x551.png 550w, https:\/\/lumieredubois.com\/wp-content\/uploads\/2025\/05\/camere-champoluc-ayas-370x370.png 370w, https:\/\/lumieredubois.com\/wp-content\/uploads\/2025\/05\/camere-champoluc-ayas-255x255.png 255w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3072b7a\" data-id=\"3072b7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8171c41 elementor-view-stacked elementor-position-inline-start elementor-widget__width-auto elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8171c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCall us\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"tel:+393339369053\">(+39) 333 936 9053<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-59285ca\" data-id=\"59285ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b206d94 elementor-view-stacked elementor-position-inline-start elementor-widget__width-auto elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b206d94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-resort\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVisit us\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/K36LZi58q5crHAUy6\">Localit\u00e0 Pracharbon snc<br>11020 Ayas (Ao)<br>Aosta Valley<br><\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-97208af\" data-id=\"97208af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8185694 elementor-view-stacked elementor-position-inline-start elementor-widget__width-auto elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8185694\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWrite to us\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"mailto:welcome@lumieredubois.com\">\nwelcome@lumieredubois.com<\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e987a7f elementor-widget elementor-widget-text-editor\" data-id=\"e987a7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>VAT No.: IT01082580075 &#8211; CIN:  <\/p><p><a href=\"https:\/\/lumieredubois.com\/privacy-policy\/\">Privacy Policy<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20b24fcd elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"20b24fcd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1a93fb40 dark-color\" data-id=\"1a93fb40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e17e1b2 elementor-widget elementor-widget-text-editor\" data-id=\"4e17e1b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a9 Copyright Lumi\u00e8re du Bois &#8211; <a href=\"https:\/\/lumieredubois.com\/privacy-policy\/\">Privacy Policy<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-35bc2d49 dark-color\" data-id=\"35bc2d49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fbc006 elementor-widget elementor-widget-text-editor\" data-id=\"8fbc006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Website by TurismOK &#8211; <a href=\"https:\/\/www.turismok.com\/\">Management &amp; Marketing for Hotels<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"template":"","custom_blocks_category":[],"class_list":["post-3930","custom_blocks","type-custom_blocks","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lumieredubois.com\/en\/wp-json\/wp\/v2\/custom_blocks\/3930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lumieredubois.com\/en\/wp-json\/wp\/v2\/custom_blocks"}],"about":[{"href":"https:\/\/lumieredubois.com\/en\/wp-json\/wp\/v2\/types\/custom_blocks"}],"version-history":[{"count":4,"href":"https:\/\/lumieredubois.com\/en\/wp-json\/wp\/v2\/custom_blocks\/3930\/revisions"}],"predecessor-version":[{"id":4395,"href":"https:\/\/lumieredubois.com\/en\/wp-json\/wp\/v2\/custom_blocks\/3930\/revisions\/4395"}],"wp:attachment":[{"href":"https:\/\/lumieredubois.com\/en\/wp-json\/wp\/v2\/media?parent=3930"}],"wp:term":[{"taxonomy":"custom_blocks_category","embeddable":true,"href":"https:\/\/lumieredubois.com\/en\/wp-json\/wp\/v2\/custom_blocks_category?post=3930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}